{"id":4072,"date":"2024-09-11T21:48:11","date_gmt":"2024-09-11T21:48:11","guid":{"rendered":"https:\/\/ibecpublishing.com\/?page_id=4072"},"modified":"2024-10-12T11:45:10","modified_gmt":"2024-10-12T11:45:10","slug":"contact-us-02","status":"publish","type":"page","link":"http:\/\/ibecpublishing.com\/en\/contact-us-02\/","title":{"rendered":"Kontakt oss"},"content":{"rendered":"<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-4061\"><form id=\"wpforms-form-4061\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"4061\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/4072\" data-token=\"c6d1c1d03dde00c0927a4e04c4ec8012\" data-token-time=\"1778704356\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/4072\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-4061-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-4061-field_8\">Fornavn <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-4061-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" aria-errormessage=\"wpforms-4061-field_8-error\" required><\/div><div id=\"wpforms-4061-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-4061-field_7\">Etternavn <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-4061-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" aria-errormessage=\"wpforms-4061-field_7-error\" required><\/div><div id=\"wpforms-4061-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-4061-field_2\">E-post <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-4061-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-4061-field_2-error\" required><\/div><div id=\"wpforms-4061-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-4061-field_6\">Firmanavn(hvis aktuelt)<\/label><input type=\"text\" id=\"wpforms-4061-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-4061-field_6-error\" ><\/div><div id=\"wpforms-4061-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-4061-field_4\">Hva handler e-posten din om? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-4061-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" aria-errormessage=\"wpforms-4061-field_4-error\" required><\/div><div id=\"wpforms-4061-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-4061-field_3\">Kommentar eller melding <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-4061-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-4061-field_3-error\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"4061\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"http:\/\/ibecpublishing.com\/en\/wp-json\/wp\/v2\/pages\/4072\"><span class=\"wpcf7-form-control-wrap kc_captcha\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-cf7ic\"><span class=\"captcha-image cf7ic-style1\" style=\"border:none;\"><span class=\"cf7ic_instructions\">Please prove you are human by selecting the <span>flag<\/span>.<span class=\"cf7ic-icon-wrapper\"><label><input type=\"radio\" name=\"kc_captcha\" value=\"e70990225671c60088e9356f010632703dcebf791be6c7d5db018372251ad9bf\" \/><i class=\"fa fa-flag\"><\/i><\/label><label><input type=\"radio\" name=\"kc_captcha\" value=\"a5e1952f6501de0285fcc0689b1766a6ec98c766953c8d1275613951eb73220b\" \/><i class=\"fa fa-heart\"><\/i><\/label><label><input type=\"radio\" name=\"kc_captcha\" value=\"616dcac749db019b03cfdbb1abe974b685f55ea3792494431c26f01215ce0bad\" \/><i class=\"fa fa-plane\"><\/i><\/label><span aria-hidden=\"true\" class=\"ai1ic-fields\"><input type=\"hidden\" name=\"cf7ic_exists\" value=\"true\"\/><input type=\"hidden\" name=\"kc_key\" value=\"4FJqD38aW21n8NaM0ybe\"><input type=\"text\" name=\"kc_honeypot\" tabindex=\"-1\" value=\"\"><\/span><\/span><\/span><\/span><\/span><\/span><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-4061\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Send\" aria-live=\"assertive\" value=\"wpforms-submit\">Send<\/button><img decoding=\"async\" src=\"http:\/\/ibecpublishing.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"Please enable JavaScript in your browser to complete this form.Please enable JavaScript in your browser to complete this form.Fornavn *Etternavn *E-post *Firmanavn(hvis aktuelt)Hva handler e-posten din om? *Kommentar eller melding [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4072","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/ibecpublishing.com\/en\/wp-json\/wp\/v2\/pages\/4072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ibecpublishing.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/ibecpublishing.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/ibecpublishing.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/ibecpublishing.com\/en\/wp-json\/wp\/v2\/comments?post=4072"}],"version-history":[{"count":5,"href":"http:\/\/ibecpublishing.com\/en\/wp-json\/wp\/v2\/pages\/4072\/revisions"}],"predecessor-version":[{"id":4175,"href":"http:\/\/ibecpublishing.com\/en\/wp-json\/wp\/v2\/pages\/4072\/revisions\/4175"}],"wp:attachment":[{"href":"http:\/\/ibecpublishing.com\/en\/wp-json\/wp\/v2\/media?parent=4072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}